{"id":3,"date":"2020-05-05T21:07:44","date_gmt":"2020-05-05T21:07:44","guid":{"rendered":"http:\/\/jars.wpengine.com\/?page_id=3"},"modified":"2024-08-21T01:52:21","modified_gmt":"2024-08-21T01:52:21","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/joinaresearchstudy.com\/es\/privacy-policy\/","title":{"rendered":"pol\u00edtica de privacidad"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Proteger su informaci\u00f3n privada es nuestra prioridad. Esta Declaraci\u00f3n de Privacidad se aplica a <a href=\"https:\/\/joinaresearchstudy.com\/es\/\">https:\/\/joinaresearchstudy.com\/<\/a> y Evolution Research Group (ERG) y rige la recopilaci\u00f3n y el uso de datos. A los efectos de esta Pol\u00edtica de privacidad, a menos que se indique lo contrario, todas las referencias a ERG incluyen <a href=\"https:\/\/joinaresearchstudy.com\/es\/\">https:\/\/joinaresearchstudy.com\/<\/a>. El sitio web de ERG es un sitio de agencia de comunicaciones digitales de servicio completo. Al utilizar el sitio ERG, usted acepta las pr\u00e1cticas utilizadas en relaci\u00f3n a los datos que se describen en esta declaraci\u00f3n.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Recopilaci\u00f3n de su informaci\u00f3n personal<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Para brindarle mejor los productos y servicios ofrecidos en nuestro Sitio, ERG puede recopilar informaci\u00f3n de identificaci\u00f3n personal, como su:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Nombre y apellido<\/li>\r\n<li>Direcci\u00f3n de correo electr\u00f3nico<\/li>\r\n<li>Empleador<\/li>\r\n<li>N\u00famero de tel\u00e9fono<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">No recopilamos ninguna informaci\u00f3n personal sobre usted a menos que usted nos la proporcione voluntariamente. Sin embargo, es posible que deba proporcionarnos cierta informaci\u00f3n personal cuando elija utilizar ciertos productos o servicios disponibles en el Sitio. Estos pueden incluir: (a) registrarse para obtener una cuenta en nuestro Sitio; (b) participar en un sorteo o concurso patrocinado por nosotros o uno de nuestros socios; (c) registrarse para recibir ofertas especiales de terceros seleccionados; (d) enviarnos un mensaje de correo electr\u00f3nico; (e) enviar su tarjeta de cr\u00e9dito u otra informaci\u00f3n de pago al realizar pedidos y comprar productos y servicios en nuestro Sitio. Es decir, utilizaremos su informaci\u00f3n para, entre otros, comunicarnos con usted en relaci\u00f3n con los servicios y\/o productos que nos haya solicitado. Tambi\u00e9n podemos recopilar informaci\u00f3n personal o no personal adicional en el futuro.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Uso de su informaci\u00f3n personal<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">ERG recopila y utiliza su informaci\u00f3n personal para operar su(s) sitio(s) web y brindarle los servicios que ha solicitado.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">ERG tambi\u00e9n puede utilizar su informaci\u00f3n de identificaci\u00f3n personal para informarle sobre otros productos o servicios disponibles de ERG y sus afiliados.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Compartir informaci\u00f3n con terceros<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">ERGno tiene que vender, alquilar o ceder sus listas de clientes a terceros.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">ERG puede compartir datos con socios confiables para ayudarlo a realizar an\u00e1lisis estad\u00edsticos, enviarle correo electr\u00f3nico o correo postal, brindarle atenci\u00f3n al cliente u organizar las entregas. Todos estos terceros tienen prohibido utilizar su informaci\u00f3n personal, excepto para proporcionar estos servicios a Lumentus, y deben mantener la confidencialidad de su informaci\u00f3n.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">ERG puede divulgar su informaci\u00f3n personal, sin previo aviso, si as\u00ed lo exige la ley o si cree de buena fe que dicha acci\u00f3n es necesaria para: (a) cumplir con los edictos de la ley o cumplir con un proceso legal notificado a ERG o al sitio; (b) proteger y defender los derechos o propiedad de Lumentus; y\/o (c) actuar bajo circunstancias extremas para proteger la seguridad personal de los usuarios de Lumentus o del p\u00fablico.<\/p>\r\n<p>ERG no comparte ni vende opciones de suscripci\u00f3n a SMS ni n\u00fameros de tel\u00e9fono para enviar SMS.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Informaci\u00f3n recopilada autom\u00e1ticamente<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Lumentus puede recopilar autom\u00e1ticamente informaci\u00f3n sobre el hardware y el software de su computadora. Esta informaci\u00f3n puede incluir: su direcci\u00f3n IP, tipo de navegador, nombres de dominio, tiempos de acceso y direcciones de sitios web de referencia. Esta informaci\u00f3n se utiliza para el funcionamiento del servicio, para mantener la calidad del servicio y para proporcionar estad\u00edsticas generales sobre el uso del sitio web de ERG.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Enlaces<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Este sitio web contiene enlaces a otros sitios. Tenga en cuenta que no somos responsables del contenido o las pr\u00e1cticas de privacidad de dichos otros sitios. Alentamos a nuestros usuarios a estar atentos cuando abandonan nuestro sitio y a leer las declaraciones de privacidad de cualquier otro sitio que recopile informaci\u00f3n de identificaci\u00f3n personal.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Ni\u00f1os menores de trece a\u00f1os<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">ERG no recopila intencionalmente informaci\u00f3n de identificaci\u00f3n personal de ni\u00f1os menores de trece a\u00f1os. Si tienes menos de trece a\u00f1os, debes pedir permiso a tus padres o tutores para utilizar este sitio web.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Comunicaciones por correo electr\u00f3nico<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">De vez en cuando, ERG puede comunicarse con usted por correo electr\u00f3nico con el fin de proporcionarle anuncios, ofertas promocionales, alertas, confirmaciones, encuestas y\/u otras comunicaciones generales.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Cambios a esta declaraci\u00f3n<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">ERG se reserva el derecho de cambiar esta Pol\u00edtica de Privacidad de vez en cuando. Le notificaremos sobre cambios significativos en la forma en que tratamos la informaci\u00f3n personal enviando un aviso a la direcci\u00f3n de correo electr\u00f3nico principal especificada en su cuenta, colocando un aviso destacado en nuestro sitio y\/o actualizando cualquier informaci\u00f3n de privacidad en esta p\u00e1gina. Su uso continuado del Sitio y\/o los Servicios disponibles a trav\u00e9s de este Sitio despu\u00e9s de dichas modificaciones constituir\u00e1 su: (a) reconocimiento de la Pol\u00edtica de Privacidad modificada; y (b) acuerdo de cumplir y estar sujeto a esa Pol\u00edtica.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Informaci\u00f3n del contacto<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">ERG agradece sus preguntas o comentarios relacionados con esta Declaraci\u00f3n de Privacidad. Si cree que ERG no se ha adherido a esta Declaraci\u00f3n, comun\u00edquese con ERG en:<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Grupo de Investigaci\u00f3n de la Evoluci\u00f3n<br \/>430 Avenida de la Monta\u00f1a, #302<br \/>Nueva Providencia, Nueva Jersey 07974<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Direcci\u00f3n de correo electr\u00f3nico:<br \/>info@ErgClinical.com<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">N\u00famero de tel\u00e9fono:<br \/>908.756.4411<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Vigente a partir del 03 de abril de 2019<\/p>","protected":false},"excerpt":{"rendered":"<p>Proteger su informaci\u00f3n privada es nuestra prioridad. Esta Declaraci\u00f3n de privacidad se aplica a https:\/\/joinaresearchstudy.com\/ y Evolution Research Group (ERG) y rige la recopilaci\u00f3n y el uso de datos. A los efectos de esta Pol\u00edtica de privacidad, a menos que se indique lo contrario, todas las referencias a ERG incluyen https:\/\/joinaresearchstudy.com\/. El sitio web de ERG es un sitio de una agencia de comunicaciones digitales de servicio completo. Al utilizar el sitio web de ERG, se le enviar\u00e1 un correo electr\u00f3nico con la informaci\u00f3n que se le proporcione. <\/p>\n<p class=\"read-more-container\"><a title=\"pol\u00edtica de privacidad\" class=\"read-more button\" href=\"https:\/\/joinaresearchstudy.com\/es\/privacy-policy\/#more-3\" aria-label=\"Leer m\u00e1s sobre Pol\u00edtica de Privacidad\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Evolution Research Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joinaresearchstudy.com\/es\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Evolution Research Group\" \/>\n<meta property=\"og:description\" content=\"Protecting your private information is our priority. This Statement of Privacy applies to https:\/\/joinaresearchstudy.com\/ and Evolution Research Group (ERG) and governs data collection and usage. For the purposes of this Privacy Policy, unless otherwise noted, all references to ERG include https:\/\/joinaresearchstudy.com\/. The ERG website is a a full-service digital communications agency site. By using the ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joinaresearchstudy.com\/es\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolution Research Group\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-21T01:52:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/joinaresearchstudy.com\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - Evolution Research Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/#website\"},\"datePublished\":\"2020-05-05T21:07:44+00:00\",\"dateModified\":\"2024-08-21T01:52:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/joinaresearchstudy.com\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/joinaresearchstudy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/#website\",\"url\":\"https:\\\/\\\/joinaresearchstudy.com\\\/\",\"name\":\"Evolution Research Group\",\"description\":\"Join a Research Study\",\"publisher\":{\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/joinaresearchstudy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/#organization\",\"name\":\"Evolution Research Group\",\"url\":\"https:\\\/\\\/joinaresearchstudy.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/joinaresearchstudy.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ERG-JARS_LOGO.png\",\"contentUrl\":\"https:\\\/\\\/joinaresearchstudy.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ERG-JARS_LOGO.png\",\"width\":587,\"height\":170,\"caption\":\"Evolution Research Group\"},\"image\":{\"@id\":\"https:\\\/\\\/joinaresearchstudy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - Evolution Research Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joinaresearchstudy.com\/es\/privacy-policy\/","og_locale":"es_MX","og_type":"article","og_title":"Privacy Policy - Evolution Research Group","og_description":"Protecting your private information is our priority. This Statement of Privacy applies to https:\/\/joinaresearchstudy.com\/ and Evolution Research Group (ERG) and governs data collection and usage. For the purposes of this Privacy Policy, unless otherwise noted, all references to ERG include https:\/\/joinaresearchstudy.com\/. The ERG website is a a full-service digital communications agency site. By using the ... Read more","og_url":"https:\/\/joinaresearchstudy.com\/es\/privacy-policy\/","og_site_name":"Evolution Research Group","article_modified_time":"2024-08-21T01:52:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/joinaresearchstudy.com\/privacy-policy\/","url":"https:\/\/joinaresearchstudy.com\/privacy-policy\/","name":"Pol\u00edtica de privacidad - Evolution Research Group","isPartOf":{"@id":"https:\/\/joinaresearchstudy.com\/#website"},"datePublished":"2020-05-05T21:07:44+00:00","dateModified":"2024-08-21T01:52:21+00:00","breadcrumb":{"@id":"https:\/\/joinaresearchstudy.com\/privacy-policy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joinaresearchstudy.com\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/joinaresearchstudy.com\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/joinaresearchstudy.com\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/joinaresearchstudy.com\/#website","url":"https:\/\/joinaresearchstudy.com\/","name":"Grupo de Investigaci\u00f3n de la Evoluci\u00f3n","description":"\u00danase a un estudio de investigaci\u00f3n","publisher":{"@id":"https:\/\/joinaresearchstudy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/joinaresearchstudy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/joinaresearchstudy.com\/#organization","name":"Grupo de Investigaci\u00f3n de la Evoluci\u00f3n","url":"https:\/\/joinaresearchstudy.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/joinaresearchstudy.com\/#\/schema\/logo\/image\/","url":"https:\/\/joinaresearchstudy.com\/wp-content\/uploads\/2020\/05\/ERG-JARS_LOGO.png","contentUrl":"https:\/\/joinaresearchstudy.com\/wp-content\/uploads\/2020\/05\/ERG-JARS_LOGO.png","width":587,"height":170,"caption":"Evolution Research Group"},"image":{"@id":"https:\/\/joinaresearchstudy.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/joinaresearchstudy.com\/es\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joinaresearchstudy.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/joinaresearchstudy.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/joinaresearchstudy.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joinaresearchstudy.com\/es\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/joinaresearchstudy.com\/es\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/joinaresearchstudy.com\/es\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}